{"id":2835,"date":"2017-11-20T17:20:18","date_gmt":"2017-11-20T17:20:18","guid":{"rendered":"https:\/\/testing.geekpower.ca\/swg\/lassurance-frais-juridiques-sapplique-lorsque-la-protection-de-responsabilite-ne-couvre-plus\/"},"modified":"2017-11-20T17:20:18","modified_gmt":"2017-11-20T17:20:18","slug":"lassurance-frais-juridiques-sapplique-lorsque-la-protection-de-responsabilite-ne-couvre-plus","status":"publish","type":"post","link":"https:\/\/swgins.com\/fr\/lassurance-frais-juridiques-sapplique-lorsque-la-protection-de-responsabilite-ne-couvre-plus\/","title":{"rendered":"L\u2019assurance frais juridiques s\u2019applique lorsque la protection de responsabilit\u00e9 ne couvre plus"},"content":{"rendered":"<p>L\u2019assurance frais juridiques prot\u00e8ge vos clients des frais juridiques et des d\u00e9penses potentielles associ\u00e9es \u00e0 leurs activit\u00e9s d\u2019affaires. Offrir une indemnit\u00e9 pour de tels frais est ce qui diff\u00e9rencie l\u2019assurance frais juridiques dans les cas de questions juridiques pr\u00e9cises qui ne sont pas habituellement couvertes par une assurance responsabilit\u00e9 professionnelle ou commerciale. En s\u2019associant \u00e0 des fournisseurs comme\u00a0<em><a href=\"https:\/\/sterlon.com\/\" target=\"_blank\" rel=\"noopener\">STERLON<\/a>\u00a0Legal Expense Insurance Specialists<\/em>, le groupe Assurance South Western Limit\u00e9 est en mesure d\u2019offrir une expertise in\u00e9gal\u00e9e dans cette cat\u00e9gorie niche de plus en plus importante. Bessy Allen, souscriptrice pour le portfolio de l\u2019assurance frais juridiques de la compagnie nous explique : \u00ab SWG est capable de travailler avec les courtiers en servant d\u2019interm\u00e9diaire \u2013 leur liaison pour l\u2019assurance frais juridiques, si vous voulez \u2013 afin de r\u00e9pondre aux questions et d\u2019agir comme repr\u00e9sentant lors des r\u00e9clamations en assurance frais juridiques. Nous r\u00e9solvons beaucoup de probl\u00e8mes pour nos courtiers afin de trouver les solutions dont ils ont besoin et nous avons re\u00e7u de fantastiques r\u00e9troactions concernant les services offerts par STERLON (sp\u00e9cialistes en assurance frais juridiques depuis 1993) en d\u00e9veloppement de produits. \u00bb Orient\u00e9 vers des \u00ab courtiers d\u2019assurance ayant des programmes de polices d\u2019envergures \u00bb, les solutions d\u2019assurance frais juridiques offertes actuellement par la compagnie impliquent une am\u00e9lioration de polices con\u00e7ue pour prot\u00e9ger les professionnels, les membres d\u2019associations et les petites et moyennes entreprises ayant besoin d\u2019une repr\u00e9sentation l\u00e9gale ou de conseils juridiques concernant des :<\/p>\n<ul>\n<li>Instances disciplinaires,<\/li>\n<li>Litiges fiscaux,<\/li>\n<li>Questions de r\u00e9glementation,<\/li>\n<li>Diff\u00e9rends de contrat,<\/li>\n<li>D\u00e9fenses p\u00e9nales,<\/li>\n<li>R\u00e9clamations pour pr\u00e9judice personnel,<\/li>\n<li>Diff\u00e9rends entre locateurs et locataires,<\/li>\n<li>Plaintes relatives aux droits de la personne,<\/li>\n<li>Conflits au travail (facultatif)<\/li>\n<\/ul>\n<p>Mais la cerise sur le g\u00e2teau, selon Mme Allen, est que cette protection offre \u00e9galement l\u2019avantage d\u2019un service t\u00e9l\u00e9phonique de consultation juridique (STCJ), qui fait partie des services de gestion des r\u00e9clamations de STERLON. \u00ab Certaines associations ont un acc\u00e8s tr\u00e8s limit\u00e9 \u00e0 des services juridiques abordables, \u00bb explique Mme Allen. \u00ab S\u2019ils font face \u00e0 un diff\u00e9rend l\u00e9gal ou \u00e0 un autre probl\u00e8me qu\u2019ils ne savent pas comment g\u00e9rer, au lieu d\u2019improviser, ils peuvent appeler \u00e0 ce num\u00e9ro et dire \u00ab Allo! Nous avons un probl\u00e8me \u2013 est-ce que vous pouvez nous offrir des conseils juridiques? \u00bb Malgr\u00e9 le fait que la protection de l\u2019assurance frais juridiques offerte par le groupe d\u2019Assurance South Western Limit\u00e9 couvre les entreprises pour les co\u00fbts juridiques, selon Mme Allen, \u00abL\u2019utilisation principale n\u2019est pas pour la poursuite en justice, mais plut\u00f4t pour des conseils t\u00e9l\u00e9phoniques, car ceux-ci pr\u00e9viennent l\u2019escalade des conflits en proc\u00e9dures judiciaires longues et co\u00fbteuses. \u00bb Le service STCJ est un num\u00e9ro sans frais qui est disponible pour tous les d\u00e9tenteurs de polices d\u2019assurance frais juridiques. Les appels sont illimit\u00e9s en nombre et en dur\u00e9e et le service est assur\u00e9 par des professionnels juridiques. Selon Mme Allen, \u00ab Les d\u00e9tenteurs de polices peuvent appeler avec toute sorte de questions et avoir acc\u00e8s aux conseils juridiques. L\u2019avocat \u00e0 l\u2019autre bout du fil est comp\u00e9tent, a une copie de la police entre les mains et est totalement au courant des r\u00e8gles et r\u00e9glementations applicables. \u00bb Mme Allen est convaincue qu\u2019un des avantages principaux de la protection d&rsquo;assurance frais juridiques offerte par le groupe d\u2019Assurance South Western Limit\u00e9 est l\u2019orientation de la gestion des risques que cette couverture offre. \u00ab La relation professionnelle qui nous permet d\u2019offrir une protection d\u2019assurance frais juridiques est en place depuis plusieurs ann\u00e9es d\u00e9j\u00e0. Le point central de cette protection, le service STCQ de STERLON, peut aider les parties \u00e0 r\u00e9gler les probl\u00e8mes avant de d\u00e9poser une plainte en plus d\u2019offrir la tranquillit\u00e9 d\u2019esprit qu\u2019une repr\u00e9sentation l\u00e9gale est offerte pour les probl\u00e8mes couverts si jamais un v\u00e9ritable conflit survient. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019assurance frais juridiques prot\u00e8ge vos clients des frais juridiques et des d\u00e9penses potentielles associ\u00e9es \u00e0 leurs activit\u00e9s d\u2019affaires. Offrir une indemnit\u00e9 pour de tels frais est ce qui diff\u00e9rencie l\u2019assurance frais juridiques dans les cas de questions juridiques pr\u00e9cises qui ne sont pas habituellement couvertes par une assurance responsabilit\u00e9 professionnelle ou commerciale. En s\u2019associant \u00e0 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2835","post","type-post","status-publish","format-standard","hentry","category-news-fr"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/posts\/2835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/comments?post=2835"}],"version-history":[{"count":0,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/posts\/2835\/revisions"}],"wp:attachment":[{"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/media?parent=2835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/categories?post=2835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/tags?post=2835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}