{"id":2833,"date":"2018-03-20T16:44:45","date_gmt":"2018-03-20T16:44:45","guid":{"rendered":"https:\/\/testing.geekpower.ca\/swg\/assurance-south-western-et-lloyds-of-london-un-partenariat-de-longue-date\/"},"modified":"2018-03-20T16:44:45","modified_gmt":"2018-03-20T16:44:45","slug":"assurance-south-western-et-lloyds-of-london-un-partenariat-de-longue-date","status":"publish","type":"post","link":"https:\/\/swgins.com\/fr\/assurance-south-western-et-lloyds-of-london-un-partenariat-de-longue-date\/","title":{"rendered":"Assurance South Western et Lloyd\u2019s of London \u2013 un partenariat de longue date"},"content":{"rendered":"<p>Fond\u00e9e en 1686, le Lloyd\u2019s of London poss\u00e8de une longue histoire dans le march\u00e9 des assurances ax\u00e9es sur les syndicats. \u00c9tant l\u2019un des premiers AGP au Canada \u00e0 viser ce march\u00e9, Assurance South Western entretient une relation d\u00e9cid\u00e9ment productive avec le Lloyd\u2019s depuis bien plus de quarante ans. Selon John Barclay, PDG de SWG, \u00ab Dans un march\u00e9 vivant des hauts et des bas, notre compagnie a su offrir une source de solutions stables \u00e0 travers les ann\u00e9es. C\u2019est l\u2019une de nos plus belles forces. \u00bb M Barclay poursuit en affirmant \u00ab Cette capacit\u00e9 toujours soutenue est le principal r\u00e9sultat du partenariat de longue date entre Assurance South Western et Lloyd\u2019s. Nous n\u2019avons pas fait de va-et-vient, nous ne sommes pas sortis du march\u00e9 pour y revenir. Ceci est tr\u00e8s bon pour nos courtiers et pour nos partenaires de London, car nous offrons une pr\u00e9sence soutenue \u00e0 travers le pays. \u00bb Directeur de succursale \u00e0 Toronto, Ghazal Hamid croit que la long\u00e9vit\u00e9 et l\u2019ampleur de la relation de SWG avec le Lloyd\u2019s sont principalement dues \u00e0 un \u00e9change allant dans les deux directions. \u00ab Plusieurs AGP essaient d\u2019avoir acc\u00e8s \u00e0 Lloyd\u2019s, \u00bb explique-t-il, \u00ab et plusieurs r\u00e9ussissent \u00e0 y avoir acc\u00e8s, mais rarement au m\u00eame niveau que SWG. \u00bb Barclay est d\u2019accord et est tr\u00e8s heureux de pr\u00e9ciser: \u00ab Notre partenariat avec le Lloyd\u2019s s\u2019est approfondi avec les ann\u00e9es, surtout dans notre transition pour devenir davantage une entreprise de souscription. Nous avons travaill\u00e9 fort pour \u00e9largir nos capacit\u00e9s sp\u00e9cialis\u00e9es depuis quelques ann\u00e9es. Et nous avons utilis\u00e9 l\u2019innovation offerte par London pour nous aider \u00e0 d\u00e9velopper des produits et offrir ces solutions \u00e0 nos courtiers. \u00bb Il est important de savoir qu\u2019Assurance South Western a tout d\u2019abord cherch\u00e9 \u00e0 \u00e9tablir une relation avec Lloyd\u2019s en raison d\u2019un march\u00e9 domestique qui n\u2019\u00e9tait pas en mesure d\u2019offrir les param\u00e8tres, la couverture, ni les termes requis pour plusieurs classes d\u2019entreprises. Mais ce qui a commenc\u00e9 tout simplement avec un acc\u00e8s aux services de gros, dit Hamid, est devenu un partenariat bien ancr\u00e9 incluant des aspects AGP \u00e9galement. \u00ab Ce que nous faisons maintenant est d\u2019assurer au nom de Lloyd\u2019s et ceci nous permet de cr\u00e9er des solutions plus innovatrices pour nos courtiers. En tant qu\u2019AGP\/grossiste faisant affaire avec un march\u00e9 de niche, nous assurons une classe de risques que les march\u00e9s domestiques ne veulent pas assurer. Avoir la capacit\u00e9 de penser rapidement est essentiel et je crois que c\u2019est la raison pour laquelle notre relation avec Lloyd\u2019s est primordiale \u00e0 notre croissance \u00e0 long terme. \u00bb \u00ab Travailler avec le Lloyd\u2019s est un processus tr\u00e8s it\u00e9ratif, \u00bb ajoute M Barclay. \u00ab Parfois un syndicat cherchera \u00e0 faire bouger des choses au Canada et ils devront trouver un partenaire avec les outils pour y arriver. En d\u2019autres occasions, nous sommes ceux qui pr\u00e9sentent un plan d\u2019affaires et cherchent des syndicats bien align\u00e9s pour le r\u00e9aliser. Une relation se d\u00e9veloppe dans les deux sens et un v\u00e9ritable \u00e9change de services est cr\u00e9\u00e9. \u00bb Hamid r\u00e9sume la relation de l\u2019entreprise avec London comme \u00e9tant une relation de r\u00e9ciprocit\u00e9. \u00ab Lloyd\u2019s cherche \u00e0 \u00e9tablir des partenariats avec des individus et des entreprises qui peuvent r\u00e9pondre aux besoins sp\u00e9ciaux, et nous faisons la m\u00eame chose. Il y a donc des compromises des deux c\u00f4t\u00e9s. \u00bb Et c\u2019est ce qui d\u00e9finit tous les partenariats fructueux \u00e0 long terme, selon lui.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fond\u00e9e en 1686, le Lloyd\u2019s of London poss\u00e8de une longue histoire dans le march\u00e9 des assurances ax\u00e9es sur les syndicats. \u00c9tant l\u2019un des premiers AGP au Canada \u00e0 viser ce march\u00e9, Assurance South Western entretient une relation d\u00e9cid\u00e9ment productive avec le Lloyd\u2019s depuis bien plus de quarante ans. Selon John Barclay, PDG de SWG, \u00ab [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2833","post","type-post","status-publish","format-standard","hentry","category-news-fr"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/posts\/2833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/comments?post=2833"}],"version-history":[{"count":0,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/posts\/2833\/revisions"}],"wp:attachment":[{"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/media?parent=2833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/categories?post=2833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/swgins.com\/fr\/wp-json\/wp\/v2\/tags?post=2833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}